{"id":1828,"date":"2026-03-17T03:49:38","date_gmt":"2026-03-17T03:49:38","guid":{"rendered":"https:\/\/limitertorque.com\/product\/pto-shaft-ratchet-torque-limiter-sa5-series-with-yoke\/"},"modified":"2026-03-17T03:49:39","modified_gmt":"2026-03-17T03:49:39","slug":"pto-shaft-ratchet-torque-limiter-sa5-series-with-yoke","status":"publish","type":"product","link":"https:\/\/limitertorque.com\/pt\/product\/pto-shaft-ratchet-torque-limiter-sa5-series-with-yoke\/","title":{"rendered":"Limitador de torque com catraca para eixo da tomada de for\u00e7a \u2013 S\u00e9rie SA5 (com garfo)"},"content":{"rendered":"<div itemscope itemtype=\"https:\/\/schema.org\/Product\" style=\"font-family:Arial,Helvetica,sans-serif;color:#333;line-height:1.7;max-width:1200px;margin:0 auto;\">\n<p><!-- Product Overview --><\/p>\n<h1 style=\"font-size:28px;color:#1a5632;border-bottom:3px solid #e8a020;padding-bottom:10px;margin-bottom:20px;\">Limitador de torque com catraca para eixo da tomada de for\u00e7a \u2013 S\u00e9rie SA5 (com garfo)<\/h1>\n<div style=\"display:flex;flex-wrap:wrap;gap:20px;margin-bottom:30px;\">\n<div style=\"flex:1;min-width:280px;\">\n<img decoding=\"async\" src=\"https:\/\/limitertorque.com\/wp-content\/uploads\/2026\/03\/pto-shaft-torque-limiter-4.webp\" alt=\"Ratchet Torque Limiter for PTO shaft - 6SA5 series\" style=\"width:100%;border-radius:8px;box-shadow:0 2px 8px rgba(0,0,0,0.12);\" loading=\"lazy\" \/>\n<\/div>\n<div style=\"flex:1;min-width:280px;\">\n<p style=\"font-size:16px;margin-bottom:10px;\">O <strong itemprop=\"name\">Limitador de torque com catraca para eixo da tomada de for\u00e7a \u2013 S\u00e9rie SA5 (com garfo)<\/strong> \u00e9 de qualidade premium <strong>limitador de torque de catraca<\/strong> Projetado especificamente para sistemas de eixo de transmiss\u00e3o PTO (Tomada de For\u00e7a) usados \u200b\u200bem m\u00e1quinas agr\u00edcolas, industriais e florestais. Tamb\u00e9m conhecido como <em>embreagem deslizante da tomada de for\u00e7a<\/em>, <em>embreagem de seguran\u00e7a da tomada de for\u00e7a<\/em>, ou <em>protetor de sobrecarga da tomada de for\u00e7a do trator<\/em>Este dispositivo protege seus equipamentos caros contra danos causados \u200b\u200bpor sobrecargas repentinas de torque, obstru\u00e7\u00f5es e travamentos operacionais.<\/p>\n<p><strong>Modelos dispon\u00edveis:<\/strong> 6SA5<\/p>\n<p><strong>Faixa de torque:<\/strong> <span itemprop=\"additionalProperty\" itemscope itemtype=\"https:\/\/schema.org\/PropertyValue\"><span itemprop=\"name\">Torque<\/span>: <span itemprop=\"value\">2000 Nm<\/span><\/span><\/p>\n<p><strong>Op\u00e7\u00f5es de spline:<\/strong> 1 3\/8\u2033 Z6<\/p>\n<p><strong>Componentes principais:<\/strong> Circlip, Retaining washer, Dust guard ring, Ball collar kit, Hub, Pawl kit (Qty.=40), Housing with yoke, Grease nipple<\/p>\n<p style=\"margin-top:15px;\"><a href=\"https:\/\/limitertorque.com\/pt\/contact\/\" style=\"display:inline-block;background-color:#e8a020;color:#fff;padding:12px 28px;border-radius:6px;text-decoration:none;font-weight:bold;font-size:15px;\">Solicite um or\u00e7amento \u2192<\/a><\/p>\n<\/div>\n<\/div>\n<p><!-- Technical Specifications --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Especifica\u00e7\u00f5es t\u00e9cnicas e dimens\u00f5es<\/h2>\n<div style=\"overflow-x:auto;-webkit-overflow-scrolling:touch;margin:15px 0 30px 0;\">\n<table style=\"width:100%;border-collapse:collapse;min-width:600px;font-size:14px;\" border=\"1\" cellpadding=\"8\" cellspacing=\"0\">\n<tr style='background-color:#1a5632;color:#fff;'>\n<th>S\u00e9rie<\/th>\n<th>Ajuste de torque (Nm)<\/th>\n<th>Spline<\/th>\n<th>A (mm)<\/th>\n<th>B (mm)<\/th>\n<\/tr>\n<tr>\n<td>6SA5<\/td>\n<td>2000<\/td>\n<td>1 3\/8\u2033Z6<\/td>\n<td>231<\/td>\n<td>22<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"font-size:13px;color:#666;\">* Todas as dimens\u00f5es em mil\u00edmetros. Valores de torque em Newton-metros (Nm). As especifica\u00e7\u00f5es das estrias seguem as normas ISO\/ASAE. Entre em contato conosco para configura\u00e7\u00f5es personalizadas.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/limitertorque.com\/wp-content\/uploads\/2026\/03\/pto-shaft-torque-limiter-1.webp\" alt=\"Limitador de torque do eixo da tomada de for\u00e7a (PTO) com catraca: desenho t\u00e9cnico e montagem.\" style=\"width:100%;max-width:700px;display:block;margin:20px auto;border-radius:8px;\" loading=\"lazy\" \/><\/p>\n<p><!-- Product Features & Selling Points --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Principais caracter\u00edsticas e vantagens<\/h2>\n<div style=\"display:flex;flex-wrap:wrap;gap:16px;margin:20px 0;\">\n<div style=\"flex:1;min-width:280px;background:#f5f9f5;border-radius:10px;padding:20px;border:1px solid #d5e8d5;\">\n<p style=\"font-size:28px;margin:0 0 8px 0;\">&#128257;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;font-size:15px;\">Configura\u00e7\u00f5es de sa\u00edda m\u00faltipla<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Dispon\u00edvel nas vers\u00f5es com garfo, eixo estriado e sa\u00edda flangeada para atender a qualquer requisito de instala\u00e7\u00e3o.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;background:#f5f9f5;border-radius:10px;padding:20px;border:1px solid #d5e8d5;\">\n<p style=\"font-size:28px;margin:0 0 8px 0;\">&#128274;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;font-size:15px;\">Prote\u00e7\u00e3o de sobrecarga de precis\u00e3o<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Calibrado para desconectar em limites de torque exatos, evitando danos dispendiosos a caixas de engrenagens, rolamentos e mecanismos de implementos.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;background:#f5f9f5;border-radius:10px;padding:20px;border:1px solid #d5e8d5;\">\n<p style=\"font-size:28px;margin:0 0 8px 0;\">&#9889;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;font-size:15px;\">Tempo de resposta r\u00e1pido<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Aciona em milissegundos ap\u00f3s o in\u00edcio da sobrecarga, minimizando a dura\u00e7\u00e3o da transfer\u00eancia de torque prejudicial para o equipamento conectado.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;background:#f5f9f5;border-radius:10px;padding:20px;border:1px solid #d5e8d5;\">\n<p style=\"font-size:28px;margin:0 0 8px 0;\">&#128295;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;font-size:15px;\">Manuten\u00e7\u00e3o e assist\u00eancia f\u00e1ceis<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">O design modular simples permite uma manuten\u00e7\u00e3o r\u00e1pida em campo com ferramentas padr\u00e3o. As pe\u00e7as de reposi\u00e7\u00e3o s\u00e3o facilmente encontradas e acess\u00edveis.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;background:#f5f9f5;border-radius:10px;padding:20px;border:1px solid #d5e8d5;\">\n<p style=\"font-size:28px;margin:0 0 8px 0;\">&#127981;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;font-size:15px;\">Materiais de Grau Industrial<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Usinado com precis\u00e3o a partir de a\u00e7o-liga endurecido com superf\u00edcies cr\u00edticas tratadas termicamente para m\u00e1xima durabilidade e vida \u00fatil.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;background:#f5f9f5;border-radius:10px;padding:20px;border:1px solid #d5e8d5;\">\n<p style=\"font-size:28px;margin:0 0 8px 0;\">&#128736;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;font-size:15px;\">Compatibilidade universal com tomadas de for\u00e7a<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">A interface padr\u00e3o de estrias Z6 de 1 3\/8\u2033 \u00e9 compat\u00edvel com todos os principais eixos de tomada de for\u00e7a (TDF) de tratores e implementos, sem necessidade de adaptadores ou modifica\u00e7\u00f5es.<\/p>\n<\/div>\n<\/div>\n<p><!-- Working Principle --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Como funciona \u2014 Princ\u00edpio de funcionamento<\/h2>\n<p style=\"font-size:15px;margin:15px 0;\">O limitador de torque tipo catraca utiliza conjuntos de linguetas com mola que se encaixam em um anel de catraca usinado com precis\u00e3o dentro da carca\u00e7a. Em condi\u00e7\u00f5es normais, as linguetas travam no perfil da catraca e transmitem o torque total. Quando ocorre uma sobrecarga e o torque excede a pr\u00e9-carga da mola, as linguetas s\u00e3o for\u00e7adas a se desengatar e a embreagem desliza, produzindo um estalo caracter\u00edstico. Assim que a sobrecarga \u00e9 eliminada, as linguetas se engatam automaticamente na catraca na pr\u00f3xima rota\u00e7\u00e3o, restaurando a transmiss\u00e3o total do torque sem qualquer interven\u00e7\u00e3o manual. O n\u00famero de linguetas determina a suavidade da a\u00e7\u00e3o da catraca e a capacidade de torque geral \u2014 mais linguetas proporcionam um deslizamento mais suave e classifica\u00e7\u00f5es mais altas.<\/p>\n<p style=\"margin:10px 0;\"><strong>M\u00e9todo de reinicializa\u00e7\u00e3o:<\/strong> Autom\u00e1tico \u2014 reinicializa automaticamente ap\u00f3s a elimina\u00e7\u00e3o da sobrecarga.<\/p>\n<p><strong>Ideal para:<\/strong> Equipamentos sujeitos a sobrecargas transit\u00f3rias frequentes, onde a reinicializa\u00e7\u00e3o sem tempo de inatividade \u00e9 cr\u00edtica.<\/p>\n<p><!-- Application Scenarios --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Cen\u00e1rios t\u00edpicos de aplica\u00e7\u00e3o agr\u00edcola<\/h2>\n<div style=\"display:flex;flex-wrap:wrap;gap:16px;margin:15px 0;\">\n<div style=\"flex:1;min-width:280px;border-left:4px solid #e8a020;padding:12px 16px;background:#fff8ed;border-radius:0 8px 8px 0;\">\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;\">Enxadas rotativas e cultivadores<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Protege a caixa de engrenagens da enxada rotativa e a tomada de for\u00e7a do trator quando as l\u00e2minas encontram pedras enterradas, ra\u00edzes ou camadas de solo compactado que podem gerar picos de torque extremos.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;border-left:4px solid #e8a020;padding:12px 16px;background:#fff8ed;border-radius:0 8px 8px 0;\">\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;\">Manure Spreaders<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Protects the beater mechanism and gearbox from overload when encountering frozen clumps, foreign objects, or uneven material distribution in the hopper.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;border-left:4px solid #e8a020;padding:12px 16px;background:#fff8ed;border-radius:0 8px 8px 0;\">\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;\">Misturadores de ra\u00e7\u00e3o e vag\u00f5es para ra\u00e7\u00e3o total misturada (TMR)<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Protege o acionamento da rosca misturadora contra danos causados \u200b\u200bpor emaranhados de barbante, blocos de ra\u00e7\u00e3o congelados ou carga excessiva que gere torque al\u00e9m dos limites de projeto.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;border-left:4px solid #e8a020;padding:12px 16px;background:#fff8ed;border-radius:0 8px 8px 0;\">\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;\">Rosca transportadora e transportadores de gr\u00e3os<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Impede a distor\u00e7\u00e3o do tubo da rosca transportadora e a falha da caixa de engrenagens quando pontes de gr\u00e3os, gr\u00e3os inchados pela umidade ou objetos estranhos criam resist\u00eancia repentina no caminho de transporte.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:280px;border-left:4px solid #e8a020;padding:12px 16px;background:#fff8ed;border-radius:0 8px 8px 0;\">\n<p style=\"font-weight:bold;color:#1a5632;margin:0 0 6px 0;\">Cavadoras de buracos para postes<\/p>\n<p style=\"font-size:13px;color:#555;margin:0;\">Absorve o impacto extremo do torque quando a broca atinge rochas, concreto enterrado ou densos emaranhados de ra\u00edzes, protegendo tanto o acionamento da broca quanto a tomada de for\u00e7a do trator.<\/p>\n<\/div>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/limitertorque.com\/wp-content\/uploads\/2026\/03\/pto-shaft-torque-limiter-3.webp\" alt=\"Limitador de torque do eixo da tomada de for\u00e7a em aplica\u00e7\u00f5es de tratores agr\u00edcolas\" style=\"width:100%;max-width:700px;display:block;margin:20px auto;border-radius:8px;\" loading=\"lazy\" \/><\/p>\n<p><!-- Type Comparison Table --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Compara\u00e7\u00e3o dos tipos de limitadores de torque<\/h2>\n<div style=\"overflow-x:auto;-webkit-overflow-scrolling:touch;margin:15px 0 30px 0;\">\n<table style=\"width:100%;border-collapse:collapse;min-width:650px;font-size:14px;\" border=\"1\" cellpadding=\"8\" cellspacing=\"0\">\n<tr style=\"background-color:#1a5632;color:#fff;\">\n<th>Recurso<\/th>\n<th>Retentor de esfera<\/th>\n<th>Disco de fric\u00e7\u00e3o<\/th>\n<th>Pino\/Parafuso de Cisalhamento<\/th>\n<th>Catraca (Garra)<\/th>\n<th>Autom\u00e1tico (Cam)<\/th>\n<\/tr>\n<tr>\n<td><strong>Faixa de torque<\/strong><\/td>\n<td>Baixo\u2013M\u00e9dio<\/td>\n<td>M\u00e9dio-Alto<\/td>\n<td>Baixo a muito alto<\/td>\n<td>Baixo\u2013Alto<\/td>\n<td>M\u00e9dio-Alto<\/td>\n<\/tr>\n<tr style=\"background:#f9f9f9;\">\n<td><strong>Faixa de velocidade<\/strong><\/td>\n<td>540\u20131000 RPM<\/td>\n<td>540\u20131000 RPM<\/td>\n<td>540\u20131000 RPM<\/td>\n<td>540\u20131000 RPM<\/td>\n<td>540\u20131000 RPM<\/td>\n<\/tr>\n<tr>\n<td><strong>M\u00e9todo de reinicializa\u00e7\u00e3o<\/strong><\/td>\n<td>Autom\u00e1tico<\/td>\n<td>Autom\u00e1tico (deslizamento)<\/td>\n<td>Manual (substituir parafuso)<\/td>\n<td>Autom\u00e1tico (catraca)<\/td>\n<td>Autom\u00e1tico (cam)<\/td>\n<\/tr>\n<tr style=\"background:#f9f9f9;\">\n<td><strong>Melhor aplicativo<\/strong><\/td>\n<td>Implementos leves<\/td>\n<td>sobrecargas moderadas frequentes<\/td>\n<td>Sobrecargas graves pouco frequentes<\/td>\n<td>sobrecargas transit\u00f3rias frequentes<\/td>\n<td>Alta utiliza\u00e7\u00e3o, sem consum\u00edveis<\/td>\n<\/tr>\n<tr>\n<td><strong>Pe\u00e7as de consumo<\/strong><\/td>\n<td>Nenhum<\/td>\n<td>Revestimentos de fric\u00e7\u00e3o (longa vida \u00fatil)<\/td>\n<td>Parafusos de cisalhamento<\/td>\n<td>Nenhum<\/td>\n<td>Nenhum<\/td>\n<\/tr>\n<tr style=\"background:#f9f9f9;\">\n<td><strong>Precis\u00e3o de torque<\/strong><\/td>\n<td>Moderado<\/td>\n<td>Bom (ajust\u00e1vel)<\/td>\n<td>Excelente (calibrado para parafusos)<\/td>\n<td>Bom<\/td>\n<td>Muito bom (ajust\u00e1vel)<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><!-- Installation & Usage Guide --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Guia de Instala\u00e7\u00e3o e Utiliza\u00e7\u00e3o<\/h2>\n<div style=\"background:#f5f9f5;border:1px solid #c5dcc5;border-radius:8px;padding:20px;margin:15px 0;\">\n<h3 style=\"color:#1a5632;font-size:17px;margin-top:0;\">Etapas de instala\u00e7\u00e3o<\/h3>\n<p><strong>Passo 1:<\/strong> Verifique se o di\u00e2metro da estria do eixo da tomada de for\u00e7a (TDF) corresponde \u00e0 especifica\u00e7\u00e3o da estria do limitador de torque (1 3\/8\u2033 Z6). Limpe cuidadosamente todas as superf\u00edcies da estria.<\/p>\n<p><strong>Etapa 2:<\/strong> Deslize o limitador de torque na estria do eixo da tomada de for\u00e7a, garantindo o encaixe completo. Fixe-o com o kit de pinos de press\u00e3o fornecido ou com os parafusos de reten\u00e7\u00e3o.<\/p>\n<p><strong>Etapa 3:<\/strong> Conecte a extremidade de sa\u00edda (garfo ou eixo estriado) ao eixo de entrada ou \u00e0 caixa de engrenagens do implemento. Certifique-se do alinhamento correto e aperte todos os fixadores com o torque recomendado.<\/p>\n<p><strong>Passo 4:<\/strong> Aplique graxa atrav\u00e9s do bico de lubrifica\u00e7\u00e3o para lubrificar a interface estriada e os componentes internos. Use graxa EP \u00e0 base de l\u00edtio (NLGI #2).<\/p>\n<p><strong>Etapa 5:<\/strong> Realize um teste em baixa velocidade para verificar o engate correto e o funcionamento suave antes de operar em pot\u00eancia m\u00e1xima.<\/p>\n<h3 style=\"color:#1a5632;font-size:17px;\">Dicas de seguran\u00e7a e manuten\u00e7\u00e3o<\/h3>\n<p>\u26a0 Sempre desengate a tomada de for\u00e7a (TDF) do trator antes de inspecionar ou realizar manuten\u00e7\u00e3o no limitador de torque.<\/p>\n<p>\u26a0 Utilize somente pe\u00e7as de reposi\u00e7\u00e3o genu\u00ednas especificadas para a sua s\u00e9rie para manter a classifica\u00e7\u00e3o de torque correta.<\/p>\n<p>\u26a0 Lubrifique novamente as conex\u00f5es estriadas a cada 8 horas de opera\u00e7\u00e3o ou conforme especificado no manual do seu equipamento.<\/p>\n<p>\u26a0 Inspecione quanto a desgaste, rachaduras ou danos antes de cada temporada. Substitua os componentes desgastados imediatamente.<\/p>\n<p>\u26a0 Nunca opere com protetores de seguran\u00e7a do eixo da tomada de for\u00e7a danificados ou ausentes.<\/p>\n<\/div>\n<p><!-- Selection Guide --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Guia de Sele\u00e7\u00e3o \u2014 Como Escolher o Modelo Certo<\/h2>\n<div style=\"background:#fff8ed;border:1px solid #e8cfa0;border-radius:8px;padding:20px;margin:15px 0;\">\n<p>A sele\u00e7\u00e3o do limitador de torque correto requer a confirma\u00e7\u00e3o dos seguintes par\u00e2metros:<\/p>\n<p><strong>\u2713 Classifica\u00e7\u00e3o de torque necess\u00e1ria (Nm):<\/strong> Combine o torque m\u00e1ximo de opera\u00e7\u00e3o do implemento com uma margem de seguran\u00e7a de 20\u201330%.<\/p>\n<p><strong>\u2713 Dimens\u00f5es da estria do eixo da tomada de for\u00e7a:<\/strong> Geralmente, utiliza-se Z6 de 1 3\/8\u2033 (6 estrias) ou Z6\/Z20 de 1 3\/4\u2033. Verifique os requisitos de estrias de entrada e sa\u00edda.<\/p>\n<p><strong>\u2713 Velocidade da TDP:<\/strong> Rota\u00e7\u00e3o padr\u00e3o de 540 RPM ou rota\u00e7\u00e3o econ\u00f4mica de 1000 RPM \u2014 confirme os requisitos do seu implemento.<\/p>\n<p><strong>\u2713 Tipo de conex\u00e3o:<\/strong> Sa\u00edda tipo garfo para tubos de eixo padr\u00e3o, eixo estriado para montagens em linha ou sa\u00edda flangeada para montagem direta na caixa de engrenagens.<\/p>\n<p><strong>\u2713 Frequ\u00eancia de sobrecarga:<\/strong> Sobrecargas frequentes favorecem os tipos de rearme autom\u00e1tico (catraca, fric\u00e7\u00e3o, autom\u00e1tico). Sobrecargas infrequentes, por\u00e9m severas, s\u00e3o adequadas para parafusos de cisalhamento.<\/p>\n<p><strong>\u2713 Condi\u00e7\u00f5es ambientais:<\/strong> Considere poeira, umidade e temperaturas extremas. Os modelos autom\u00e1ticos selados e de fric\u00e7\u00e3o oferecem prote\u00e7\u00e3o superior em ambientes agressivos.<\/p>\n<p style=\"margin-top:15px;\">Precisa de ajuda para escolher? <a href=\"https:\/\/limitertorque.com\/pt\/contact\/\" style=\"color:#1a5632;font-weight:bold;\">Entre em contato com nossa equipe de engenharia.<\/a> Para obter assist\u00eancia personalizada na sele\u00e7\u00e3o.<\/p>\n<\/div>\n<p><!-- Quality Certification --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Certifica\u00e7\u00e3o de Qualidade e Compromisso de Servi\u00e7o<\/h2>\n<div style=\"display:flex;flex-wrap:wrap;gap:16px;margin:15px 0;\">\n<div style=\"flex:1;min-width:200px;background:#f5f9f5;border-radius:8px;padding:15px;text-align:center;\">\n<p style=\"font-size:32px;margin:0;\">&#9989;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;\">ISO 9001:2015<\/p>\n<p style=\"font-size:13px;\">Sistema de gest\u00e3o da qualidade certificado, garantindo excel\u00eancia consistente do produto.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:200px;background:#f5f9f5;border-radius:8px;padding:15px;text-align:center;\">\n<p style=\"font-size:32px;margin:0;\">&#9989;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;\">Com marca\u00e7\u00e3o CE<\/p>\n<p style=\"font-size:13px;\">Em conformidade com as normas europeias de seguran\u00e7a, sa\u00fade e prote\u00e7\u00e3o ambiental.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:200px;background:#f5f9f5;border-radius:8px;padding:15px;text-align:center;\">\n<p style=\"font-size:32px;margin:0;\">&#128170;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;\">Garantia de 12 meses<\/p>\n<p style=\"font-size:13px;\">Garantia total contra defeitos de fabrica\u00e7\u00e3o em condi\u00e7\u00f5es normais de opera\u00e7\u00e3o.<\/p>\n<\/div>\n<div style=\"flex:1;min-width:200px;background:#f5f9f5;border-radius:8px;padding:15px;text-align:center;\">\n<p style=\"font-size:32px;margin:0;\">&#128666;<\/p>\n<p style=\"font-weight:bold;color:#1a5632;\">Envio internacional<\/p>\n<p style=\"font-size:13px;\">Entrega r\u00e1pida em todo o mundo com embalagem e documenta\u00e7\u00e3o profissionais para exporta\u00e7\u00e3o.<\/p>\n<\/div>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/limitertorque.com\/wp-content\/uploads\/2024\/01\/pto-drive-shaft-production-workshop.jpg\" alt=\"Oficina de fabrica\u00e7\u00e3o de limitadores de torque do eixo de acionamento da tomada de for\u00e7a\" style=\"width:100%;max-width:700px;display:block;margin:20px auto;border-radius:8px;\" loading=\"lazy\" \/><\/p>\n<p><!-- FAQ Section --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Perguntas frequentes (FAQ)<\/h2>\n<div itemscope itemtype=\"https:\/\/schema.org\/FAQPage\" style=\"margin:15px 0;\">\n<div itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" style=\"margin-bottom:5px;\">\n<details style=\"border:1px solid #e0e0e0;border-radius:8px;overflow:hidden;\">\n<summary style=\"padding:14px 18px;background:#f5f9f5;cursor:pointer;font-weight:bold;color:#1a5632;font-size:15px;list-style:none;\" itemprop=\"name\">Qual o torque recomendado para o meu implemento?<\/summary>\n<div itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" style=\"padding:14px 18px;\">\n<p itemprop=\"text\" style=\"margin:0;font-size:14px;color:#444;\">A classifica\u00e7\u00e3o de torque necess\u00e1ria depende do torque m\u00e1ximo de opera\u00e7\u00e3o do seu implemento. Como regra geral, selecione um limitador de torque com classifica\u00e7\u00e3o de 1,2 a 1,5 vezes o torque m\u00e1ximo de opera\u00e7\u00e3o normal do implemento. Consulte as especifica\u00e7\u00f5es do fabricante do seu implemento ou entre em contato com nossa equipe de engenharia para obter orienta\u00e7\u00e3o personalizada.<\/p>\n<\/div>\n<\/details>\n<\/div>\n<div itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" style=\"margin-bottom:5px;\">\n<details style=\"border:1px solid #e0e0e0;border-radius:8px;overflow:hidden;\">\n<summary style=\"padding:14px 18px;background:#f5f9f5;cursor:pointer;font-weight:bold;color:#1a5632;font-size:15px;list-style:none;\" itemprop=\"name\">Como posso saber quando o limitador de torque foi ativado?<\/summary>\n<div itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" style=\"padding:14px 18px;\">\n<p itemprop=\"text\" style=\"margin:0;font-size:14px;color:#444;\">Dependendo do tipo: os limitadores de parafuso de cisalhamento apresentam um parafuso visivelmente rompido; os limitadores de catraca produzem um estalo distinto durante o deslizamento; os limitadores de fric\u00e7\u00e3o emitem um leve odor e som durante o deslizamento prolongado; os limitadores de came autom\u00e1ticos produzem uma sensa\u00e7\u00e3o de estalo. Em todos os casos, o implemento para de receber pot\u00eancia enquanto o eixo da tomada de for\u00e7a continua girando.<\/p>\n<\/div>\n<\/details>\n<\/div>\n<div itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" style=\"margin-bottom:5px;\">\n<details style=\"border:1px solid #e0e0e0;border-radius:8px;overflow:hidden;\">\n<summary style=\"padding:14px 18px;background:#f5f9f5;cursor:pointer;font-weight:bold;color:#1a5632;font-size:15px;list-style:none;\" itemprop=\"name\">Posso ajustar a configura\u00e7\u00e3o de torque?<\/summary>\n<div itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" style=\"padding:14px 18px;\">\n<p itemprop=\"text\" style=\"margin:0;font-size:14px;color:#444;\">Os limitadores de torque do tipo fric\u00e7\u00e3o e autom\u00e1ticos (tipo came) permitem o ajuste do torque em campo, alterando a pr\u00e9-carga da mola atrav\u00e9s da tens\u00e3o do parafuso. Os limitadores de torque do tipo parafuso de cisalhamento s\u00e3o definidos pela classe do parafuso e n\u00e3o podem ser ajustados \u2014 diferentes classifica\u00e7\u00f5es de torque exigem diferentes especifica\u00e7\u00f5es de parafuso. Os limitadores do tipo catraca t\u00eam uma configura\u00e7\u00e3o fixa determinada pelo n\u00famero e pela constante el\u00e1stica das linguetas.<\/p>\n<\/div>\n<\/details>\n<\/div>\n<div itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" style=\"margin-bottom:5px;\">\n<details style=\"border:1px solid #e0e0e0;border-radius:8px;overflow:hidden;\">\n<summary style=\"padding:14px 18px;background:#f5f9f5;cursor:pointer;font-weight:bold;color:#1a5632;font-size:15px;list-style:none;\" itemprop=\"name\">Que tipo de manuten\u00e7\u00e3o \u00e9 necess\u00e1ria para o limitador de torque?<\/summary>\n<div itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" style=\"padding:14px 18px;\">\n<p itemprop=\"text\" style=\"margin:0;font-size:14px;color:#444;\">A lubrifica\u00e7\u00e3o regular atrav\u00e9s do bico de lubrifica\u00e7\u00e3o (a cada 8 horas de funcionamento), a inspe\u00e7\u00e3o visual para verificar desgaste ou danos antes de cada temporada e a substitui\u00e7\u00e3o dos revestimentos de fric\u00e7\u00e3o desgastados (tipos de fric\u00e7\u00e3o) ou a manuten\u00e7\u00e3o de parafusos de cisalhamento sobressalentes (tipos de parafuso de cisalhamento) s\u00e3o recomendadas. Os tipos autom\u00e1ticos e de catraca requerem manuten\u00e7\u00e3o m\u00ednima al\u00e9m da lubrifica\u00e7\u00e3o.<\/p>\n<\/div>\n<\/details>\n<\/div>\n<div itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" style=\"margin-bottom:5px;\">\n<details style=\"border:1px solid #e0e0e0;border-radius:8px;overflow:hidden;\">\n<summary style=\"padding:14px 18px;background:#f5f9f5;cursor:pointer;font-weight:bold;color:#1a5632;font-size:15px;list-style:none;\" itemprop=\"name\">Este limitador de torque \u00e9 compat\u00edvel com o meu eixo da tomada de for\u00e7a?<\/summary>\n<div itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" style=\"padding:14px 18px;\">\n<p itemprop=\"text\" style=\"margin:0;font-size:14px;color:#444;\">Este produto utiliza conex\u00f5es estriadas padr\u00e3o Z6 de 1 3\/8\u2033, compat\u00edveis com a grande maioria dos eixos de tomada de for\u00e7a (TDF) agr\u00edcolas em todo o mundo. Caso seu equipamento utilize uma configura\u00e7\u00e3o de estrias diferente, oferecemos adaptadores e op\u00e7\u00f5es de estrias personalizadas. Entre em contato conosco com as especifica\u00e7\u00f5es do seu eixo para confirma\u00e7\u00e3o.<\/p>\n<\/div>\n<\/details>\n<\/div>\n<div itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" style=\"margin-bottom:5px;\">\n<details style=\"border:1px solid #e0e0e0;border-radius:8px;overflow:hidden;\">\n<summary style=\"padding:14px 18px;background:#f5f9f5;cursor:pointer;font-weight:bold;color:#1a5632;font-size:15px;list-style:none;\" itemprop=\"name\">Qual a diferen\u00e7a entre uma tomada de for\u00e7a (TDF) de 540 RPM e uma de 1000 RPM?<\/summary>\n<div itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" style=\"padding:14px 18px;\">\n<p itemprop=\"text\" style=\"margin:0;font-size:14px;color:#444;\">A tomada de for\u00e7a (TDF) padr\u00e3o opera a 540 RPM e \u00e9 utilizada na maioria dos implementos agr\u00edcolas. A TDF econ\u00f4mica (tamb\u00e9m chamada de TDF de 1000 RPM) \u00e9 utilizada em implementos mais leves para reduzir a rota\u00e7\u00e3o do motor e o consumo de combust\u00edvel. Nossos limitadores de torque s\u00e3o dimensionados para ambas as velocidades. Selecione o tamanho da estria correspondente ao padr\u00e3o da sua TDF: normalmente 1 3\/8\u2033 Z6 para 540 RPM e 1 3\/4\u2033 Z20 para 1000 RPM.<\/p>\n<\/div>\n<\/details>\n<\/div>\n<div itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\" style=\"margin-bottom:5px;\">\n<details style=\"border:1px solid #e0e0e0;border-radius:8px;overflow:hidden;\">\n<summary style=\"padding:14px 18px;background:#f5f9f5;cursor:pointer;font-weight:bold;color:#1a5632;font-size:15px;list-style:none;\" itemprop=\"name\">Voc\u00eas oferecem fabrica\u00e7\u00e3o OEM e de marca pr\u00f3pria?<\/summary>\n<div itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" style=\"padding:14px 18px;\">\n<p itemprop=\"text\" style=\"margin:0;font-size:14px;color:#444;\">Sim, oferecemos servi\u00e7os completos de fabrica\u00e7\u00e3o OEM, incluindo classifica\u00e7\u00f5es de torque personalizadas, configura\u00e7\u00f5es especiais de estrias, marca\u00e7\u00f5es personalizadas e embalagens de marca pr\u00f3pria. Quantidades m\u00ednimas de pedido se aplicam. Entre em contato com nossa equipe de vendas pelo link abaixo para discutir suas necessidades.<\/p>\n<\/div>\n<\/details>\n<\/div>\n<\/div>\n<p><!-- Customer Reviews --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">O que dizem nossos clientes<\/h2>\n<div style=\"margin:15px 0;\">\n<div style=\"border:1px solid #e8e8e8;border-radius:8px;padding:16px;margin-bottom:12px;background:#fafafa;\">\n<p style=\"margin:0 0 6px 0;\"><span style=\"font-size:18px;\">&#127462;&#127479;<\/span> <strong>Miguel R.<\/strong> \u2014 <em>Gerente de fazenda, Prov\u00edncia de Buenos Aires, Argentina<\/em><\/p>\n<p style=\"margin:0;font-size:14px;color:#444;\">\u201cDurabilidade excepcional em nossas condi\u00e7\u00f5es empoeiradas da regi\u00e3o dos Pampas. Estamos usando esses pneus h\u00e1 dois anos em transportadores de gr\u00e3os e misturadores de ra\u00e7\u00e3o, sem nenhuma falha. O design selado impede a entrada de poeira.\u201d<\/p>\n<p style=\"margin:5px 0 0 0;color:#e8a020;\">&#9733;&#9733;&#9733;&#9733;&#9733;<\/p>\n<\/div>\n<div style=\"border:1px solid #e8e8e8;border-radius:8px;padding:16px;margin-bottom:12px;background:#fafafa;\">\n<p style=\"margin:0 0 6px 0;\"><span style=\"font-size:18px;\">&#127482;&#127480;<\/span> <strong>David H.<\/strong> \u2014 <em>Revendedor de equipamentos, Iowa, Estados Unidos<\/em><\/p>\n<p style=\"margin:0;font-size:14px;color:#444;\">\u201cNossos clientes sempre voltam para comprar esses produtos. A qualidade se iguala ou supera a das marcas OEM europeias, por uma fra\u00e7\u00e3o do pre\u00e7o. Temos em estoque toda a linha para aplica\u00e7\u00f5es em colheitadeiras, enfardadeiras e segadoras.\u201d<\/p>\n<p style=\"margin:5px 0 0 0;color:#e8a020;\">&#9733;&#9733;&#9733;&#9733;&#9733;<\/p>\n<\/div>\n<div style=\"border:1px solid #e8e8e8;border-radius:8px;padding:16px;margin-bottom:12px;background:#fafafa;\">\n<p style=\"margin:0 0 6px 0;\"><span style=\"font-size:18px;\">&#127475;&#127487;<\/span> <strong>Craig W.<\/strong> \u2014 <em>Produtor de leite, Waikato, Nova Zel\u00e2ndia<\/em><\/p>\n<p style=\"margin:0;font-size:14px;color:#444;\">\u201cEstamos usando esses dispositivos em nossos ro\u00e7adores de pasto e vag\u00f5es de ra\u00e7\u00e3o. Eles j\u00e1 evitaram danos aos nossos eixos de tomada de for\u00e7a diversas vezes ao atingir tocos escondidos. Design genial \u2014 o rearme autom\u00e1tico significa que n\u00e3o perdemos tempo de ordenha.\u201d<\/p>\n<p style=\"margin:5px 0 0 0;color:#e8a020;\">&#9733;&#9733;&#9733;&#9733;&#9733;<\/p>\n<\/div>\n<div style=\"border:1px solid #e8e8e8;border-radius:8px;padding:16px;margin-bottom:12px;background:#fafafa;\">\n<p style=\"margin:0 0 6px 0;\"><span style=\"font-size:18px;\">&#127468;&#127463;<\/span> <strong>William D.<\/strong> \u2014 <em>Empreiteiro agr\u00edcola, Yorkshire, Reino Unido<\/em><\/p>\n<p style=\"margin:0;font-size:14px;color:#444;\">\u201cQualidade de fabrica\u00e7\u00e3o de primeira linha. Estes engates encaixam perfeitamente nos eixos de tomada de for\u00e7a padr\u00e3o do Reino Unido e as classifica\u00e7\u00f5es de torque s\u00e3o exatas. Instalei-os em cultivadores, semeadoras e cortadores de grama \u2014 todos funcionando perfeitamente.\u201d<\/p>\n<p style=\"margin:5px 0 0 0;color:#e8a020;\">&#9733;&#9733;&#9733;&#9733;&#9733;<\/p>\n<\/div>\n<div style=\"border:1px solid #e8e8e8;border-radius:8px;padding:16px;margin-bottom:12px;background:#fafafa;\">\n<p style=\"margin:0 0 6px 0;\"><span style=\"font-size:18px;\">&#127462;&#127482;<\/span> <strong>James M.<\/strong> \u2014 <em>Produtor de gr\u00e3os, Nova Gales do Sul, Austr\u00e1lia<\/em><\/p>\n<p style=\"margin:0;font-size:14px;color:#444;\">\u201cInstalamos esses limitadores de torque em todas as nossas transmiss\u00f5es de colheitadeiras depois de perdermos uma caixa de engrenagens na \u00faltima safra. Eles foram acionados duas vezes por pedras escondidas e nos economizaram milhares em reparos em cada ocasi\u00e3o. Equipamento absolutamente essencial para a agricultura extensiva australiana.\u201d<\/p>\n<p style=\"margin:5px 0 0 0;color:#e8a020;\">&#9733;&#9733;&#9733;&#9733;&#9733;<\/p>\n<\/div>\n<\/div>\n<p><!-- Related Products --><\/p>\n<h2 style=\"font-size:22px;color:#1a5632;margin-top:35px;border-left:4px solid #e8a020;padding-left:12px;\">Produtos e acess\u00f3rios relacionados ao eixo da tomada de for\u00e7a<\/h2>\n<div style=\"display:flex;flex-wrap:wrap;gap:16px;margin:15px 0;\">\n<div style=\"flex:1;min-width:220px;border:1px solid #e0e0e0;border-radius:8px;padding:15px;text-align:center;\">\n<img decoding=\"async\" src=\"https:\/\/limitertorque.com\/wp-content\/uploads\/2024\/01\/related-pto-shaft-parts.webp\" alt=\"Pe\u00e7as e acess\u00f3rios para eixo da tomada de for\u00e7a\" style=\"width:100%;border-radius:6px;margin-bottom:10px;\" loading=\"lazy\" \/><\/p>\n<p style=\"font-weight:bold;color:#1a5632;\">Componentes do eixo da tomada de for\u00e7a<\/p>\n<p style=\"font-size:13px;\">Gama completa de garfos de eixo de tomada de for\u00e7a (TDF), rolamentos transversais, tubos, prote\u00e7\u00f5es e adaptadores para todos os tamanhos padr\u00e3o.<\/p>\n<p><a href=\"https:\/\/shaft-pto.com\" style=\"color:#e8a020;font-weight:bold;\" target=\"_blank\" rel=\"noopener\">Veja os eixos da tomada de for\u00e7a \u2192<\/a><\/p>\n<\/div>\n<div style=\"flex:1;min-width:220px;border:1px solid #e0e0e0;border-radius:8px;padding:15px;text-align:center;\">\n<img decoding=\"async\" src=\"https:\/\/limitertorque.com\/wp-content\/uploads\/2024\/01\/pto-shaft-and-gearbox.webp\" alt=\"Eixo da tomada de for\u00e7a e conjunto da caixa de engrenagens agr\u00edcola\" style=\"width:100%;border-radius:6px;margin-bottom:10px;\" loading=\"lazy\" \/><\/p>\n<p style=\"font-weight:bold;color:#1a5632;\">Caixas de Engrenagens Agr\u00edcolas<\/p>\n<p style=\"font-size:13px;\">Caixas de engrenagens combinadas, projetadas para funcionar perfeitamente com nossos eixos de tomada de for\u00e7a e limitadores de torque.<\/p>\n<p><a href=\"https:\/\/limitertorque.com\/pt\/\" style=\"color:#e8a020;font-weight:bold;\">Explorar Produtos \u2192<\/a><\/p>\n<\/div>\n<div style=\"flex:1;min-width:220px;border:1px solid #e0e0e0;border-radius:8px;padding:15px;\">\n<p style=\"font-weight:bold;color:#1a5632;\">Acess\u00f3rios para tomada de for\u00e7a dispon\u00edveis:<\/p>\n<p style=\"font-size:13px;\">\u2022 Garfos do eixo da tomada de for\u00e7a (furo liso, estriado, de libera\u00e7\u00e3o r\u00e1pida)<\/p>\n<p style=\"font-size:13px;\">\u2022 Escudos de seguran\u00e7a e tubos de prote\u00e7\u00e3o (em conformidade com a norma EN 12965)<\/p>\n<p style=\"font-size:13px;\">\u2022 Adaptadores de encaixe (convers\u00e3o de 1 3\/8\u2033 para 1 3\/4\u2033)<\/p>\n<p style=\"font-size:13px;\">\u2022 Kits de rolamentos transversais e kits de reparo de juntas universais<\/p>\n<p style=\"font-size:13px;\">\u2022 Tubos telesc\u00f3picos para eixo de tomada de for\u00e7a (perfil triangular e em formato de lim\u00e3o)<\/p>\n<p style=\"font-size:13px;\">\u2022 Kits de pinos de press\u00e3o e ferragens de fixa\u00e7\u00e3o<\/p>\n<\/div>\n<\/div>\n<p><!-- Call to Action --><\/p>\n<div style=\"background:linear-gradient(135deg,#1a5632,#2d8a56);color:#fff;padding:30px;border-radius:10px;text-align:center;margin:35px 0;\">\n<h2 style=\"font-size:24px;margin:0 0 10px 0;color:#fff;\">Pronto para proteger seu equipamento?<\/h2>\n<p style=\"font-size:16px;margin-bottom:20px;color:#e0f0e0;\">Seja para uma \u00fanica unidade de reposi\u00e7\u00e3o ou para fornecimento em grande escala para fabricantes de equipamentos originais (OEM), nossa equipe est\u00e1 pronta para ajud\u00e1-lo a selecionar o limitador de torque ideal para sua aplica\u00e7\u00e3o. Oferecemos pre\u00e7os competitivos para empresas (B2B), consultoria t\u00e9cnica e entrega r\u00e1pida em todo o mundo.<\/p>\n<p><a href=\"https:\/\/limitertorque.com\/pt\/contact\/\" style=\"display:inline-block;background-color:#e8a020;color:#fff;padding:14px 36px;border-radius:8px;text-decoration:none;font-weight:bold;font-size:17px;margin:5px;\">Solicite um or\u00e7amento gratuito \u2192<\/a><br \/>\n<a href=\"https:\/\/limitertorque.com\/pt\/\" style=\"display:inline-block;background-color:transparent;color:#fff;padding:14px 36px;border-radius:8px;text-decoration:none;font-weight:bold;font-size:17px;border:2px solid #fff;margin:5px;\">Veja todos os produtos<\/a><\/p>\n<p style=\"font-size:13px;margin-top:15px;color:#c0dcc0;\">Parcerias com fabricantes de equipamentos originais (OEM) e distribuidores s\u00e3o bem-vindas \u00b7 Pedido m\u00ednimo de apenas 10 unidades \u00b7 Especifica\u00e7\u00f5es personalizadas dispon\u00edveis<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>O <strong>SA5 Series Ratchet Torque Limiter<\/strong> represents the highest torque capacity in the ratchet limiter range, rated at <strong>2000 Nm<\/strong>. With 40 pawl kits delivering maximum engagement area and load distribution, it provides exceptional protection for the largest PTO-driven agricultural and industrial equipment. This yoke-type unit fits standard 1 3\/8&#8243; Z6 spline PTO shafts and features automatic re-engagement for uninterrupted field operation. <em>Industry-leading 40-pawl system<\/em>, <em>maximum torque protection<\/em>, e <em>automatic reset with zero downtime<\/em> make the SA5 the definitive choice for extreme-duty PTO overload protection.<\/p>","protected":false},"featured_media":1776,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[5074],"product_tag":[5081,5076,5080,5077,5082,5075,5084,5079,5078,5083],"class_list":{"0":"post-1828","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ratchet-torque-limiter","7":"product_tag-agricultural-ratchet-overload-clutch","8":"product_tag-auto-reset-pto-clutch","9":"product_tag-automatic-re-engage-torque-limiter","10":"product_tag-pawl-type-torque-limiter","11":"product_tag-pto-driveline-ratchet-protector","12":"product_tag-pto-ratchet-torque-limiter","13":"product_tag-pto-shaft-auto-reset-coupling","14":"product_tag-pto-shaft-ratchet-slip-clutch","15":"product_tag-self-resetting-pto-safety-clutch","16":"product_tag-spring-loaded-pawl-torque-limiter","18":"first","19":"instock","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/product\/1828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/comments?post=1828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/media\/1776"}],"wp:attachment":[{"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/media?parent=1828"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/product_brand?post=1828"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/product_cat?post=1828"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/limitertorque.com\/pt\/wp-json\/wp\/v2\/product_tag?post=1828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}